{"id":27034,"date":"2026-05-11T07:45:12","date_gmt":"2026-05-11T07:45:12","guid":{"rendered":"https:\/\/www.claldy.com.uy\/?p=27034"},"modified":"2026-05-11T07:45:20","modified_gmt":"2026-05-11T07:45:20","slug":"27034-2","status":"publish","type":"post","link":"https:\/\/www.claldy.com.uy\/en\/27034-2\/","title":{"rendered":""},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.claldy.com.uy\/es\/wp-json\/wp\/v2\/posts\/27034\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espa\u00f1ol<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Espa\u00f1ol.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27034","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>- Claldy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.claldy.com.uy\/27034-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Claldy\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Espa\u00f1ol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.claldy.com.uy\/27034-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Claldy\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T07:45:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T07:45:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/admiral-kz.doshik.kz\/images\/preview\/admiral-h-kazino-onlajn-fe5ee8-57.webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.claldy.com.uy\/27034-2\/\",\"url\":\"https:\/\/www.claldy.com.uy\/27034-2\/\",\"name\":\"- Claldy\",\"isPartOf\":{\"@id\":\"https:\/\/www.claldy.com.uy\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.claldy.com.uy\/27034-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.claldy.com.uy\/27034-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/admiral-kz.doshik.kz\/images\/preview\/admiral-h-kazino-onlajn-fe5ee8-57.webp\",\"datePublished\":\"2026-05-11T07:45:12+00:00\",\"dateModified\":\"2026-05-11T07:45:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.claldy.com.uy\/es\/#\/schema\/person\/84474442b2301d514b148de446aa44e0\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.claldy.com.uy\/27034-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.claldy.com.uy\/27034-2\/#primaryimage\",\"url\":\"https:\/\/admiral-kz.doshik.kz\/images\/preview\/admiral-h-kazino-onlajn-fe5ee8-57.webp\",\"contentUrl\":\"https:\/\/admiral-kz.doshik.kz\/images\/preview\/admiral-h-kazino-onlajn-fe5ee8-57.webp\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.claldy.com.uy\/es\/#website\",\"url\":\"https:\/\/www.claldy.com.uy\/es\/\",\"name\":\"Claldy\",\"description\":\"Young Dairymen\u00b4s Agricultural Dairy-farm Company\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.claldy.com.uy\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.claldy.com.uy\/es\/#\/schema\/person\/84474442b2301d514b148de446aa44e0\",\"name\":\"admin\",\"url\":\"https:\/\/www.claldy.com.uy\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Claldy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.claldy.com.uy\/27034-2\/","og_locale":"en_US","og_type":"article","og_title":"- Claldy","og_description":"Sorry, this entry is only available in Espa\u00f1ol.","og_url":"https:\/\/www.claldy.com.uy\/27034-2\/","og_site_name":"Claldy","article_published_time":"2026-05-11T07:45:12+00:00","article_modified_time":"2026-05-11T07:45:20+00:00","og_image":[{"url":"https:\/\/admiral-kz.doshik.kz\/images\/preview\/admiral-h-kazino-onlajn-fe5ee8-57.webp","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.claldy.com.uy\/27034-2\/","url":"https:\/\/www.claldy.com.uy\/27034-2\/","name":"- Claldy","isPartOf":{"@id":"https:\/\/www.claldy.com.uy\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.claldy.com.uy\/27034-2\/#primaryimage"},"image":{"@id":"https:\/\/www.claldy.com.uy\/27034-2\/#primaryimage"},"thumbnailUrl":"https:\/\/admiral-kz.doshik.kz\/images\/preview\/admiral-h-kazino-onlajn-fe5ee8-57.webp","datePublished":"2026-05-11T07:45:12+00:00","dateModified":"2026-05-11T07:45:20+00:00","author":{"@id":"https:\/\/www.claldy.com.uy\/es\/#\/schema\/person\/84474442b2301d514b148de446aa44e0"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.claldy.com.uy\/27034-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.claldy.com.uy\/27034-2\/#primaryimage","url":"https:\/\/admiral-kz.doshik.kz\/images\/preview\/admiral-h-kazino-onlajn-fe5ee8-57.webp","contentUrl":"https:\/\/admiral-kz.doshik.kz\/images\/preview\/admiral-h-kazino-onlajn-fe5ee8-57.webp"},{"@type":"WebSite","@id":"https:\/\/www.claldy.com.uy\/es\/#website","url":"https:\/\/www.claldy.com.uy\/es\/","name":"Claldy","description":"Young Dairymen\u00b4s Agricultural Dairy-farm Company","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.claldy.com.uy\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.claldy.com.uy\/es\/#\/schema\/person\/84474442b2301d514b148de446aa44e0","name":"admin","url":"https:\/\/www.claldy.com.uy\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/posts\/27034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/comments?post=27034"}],"version-history":[{"count":1,"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/posts\/27034\/revisions"}],"predecessor-version":[{"id":27035,"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/posts\/27034\/revisions\/27035"}],"wp:attachment":[{"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/media?parent=27034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/categories?post=27034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claldy.com.uy\/en\/wp-json\/wp\/v2\/tags?post=27034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}